{"id":43786,"date":"2023-08-09T19:27:56","date_gmt":"2023-08-09T17:27:56","guid":{"rendered":"https:\/\/canfali.com\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/"},"modified":"2025-02-25T10:01:22","modified_gmt":"2025-02-25T09:01:22","slug":"pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/","title":{"rendered":"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios"},"content":{"rendered":"<p>La proximidad del aniversario del incendio forestal que desde el 13 de agosto de 2022 y durante interminables jornadas calcin&oacute; m&aacute;s de 11.300 hect&aacute;reas en el interior norte de la Marina Alta, y las vecinas comarcas de El Comtat i la Safor ha motivado al Ayuntamiento de Pego a dar cuenta de las diferentes estrategias emprendidas en los &uacute;ltimos meses para evitar la repetici&oacute;n de este tipo de cat&aacute;strofes medioambientales y paisaj&iacute;sticas.<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Desde el consistorio pegolino han recordado esta semana que, pese a la brutalidad de los hechos, el fuego sac&oacute; lo mejor del tejido social que se volc&oacute; en colaborar con los afectados que resultaron desalojados y con los medios que trabajaban en la extinci&oacute;n tanto de la parte del t&eacute;rmino municipal como de los vecinos.<\/p>\n<p>Seg&uacute;n apuntan, la extinci&oacute;n del siniestro fue considerado como una lecci&oacute;n y motiv&oacute; el impulso a un paquete de medidas de prevenci&oacute;n como la revisi&oacute;n y actualizaci&oacute;n del Plan de Emergencias de Incendios Forestales y el Plan Territorial de Emergencias, que han sido completados en los &uacute;ltimos meses por una empresa especializada.<\/p>\n<p>Adem&aacute;s de ello se ha procedido a la revisi&oacute;n de los hidrantes existentes en el t&eacute;rmino municipal tanto en el casco urbano como en la zona r&uacute;stica con el fin de confirmar que se encuentran en &oacute;ptimas condiciones para un potencial uso. Esta actuaci&oacute;n, acometida con la oportuna subvenci&oacute;n, ha sido complementada con la georeferencia de todos los integrantes de la infraesctructura para facilitar su r&aacute;pida localizaci&oacute;n a fin de agilizar las labores de extinci&oacute;n por parte de las brigadas antiincendios.<\/p>\n<p>&nbsp;<\/p>\n<p>CORTAFUEGOS Y ACTIVIDADES DE REFORESTACI&Oacute;N<\/p>\n<p>&nbsp;<\/p>\n<p>Asimismo, des del Ayuntamiento han confirmado la gesti&oacute;n de las oportunas ayudas de administraciones supramunicipales para la habilitaci&oacute;n de cortafuegos, que ha sido asumidas por una empresa con experiencia en este tipo de labores. En concreto, han apuntado que las primeras tareas en este sentido han tenido como escenario la zona &nbsp;&nbsp;<\/p>\n<p>verde situada en el paraje del Carritxar, si bien est&aacute; prevista su reanudaci&oacute;n a medida que bajen las temperaturas y se desactiven las alertas por posibles incendios.<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Esta din&aacute;mica ha comportado la renovaci&oacute;n de acuerdos colaboraci&oacute;n con entidades y asociaciones, como Pego Viu, a la que se le han cedido cinco parcelas municipales ubicadas en zonas como &nbsp;Xical, Mitjanes, Pla de la Mata y Salomona con el fin de que sean destinadas a proyectos de reforestaci&oacute;n.<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; &ldquo;Desde el Ayuntamiento se quiere agradecer a todas las personas, a t&iacute;tulo individual como los cargos p&uacute;blicos; entidades p&uacute;blicas y asociaciones, y empresas privadas todo el esfuerzo de aquellos d&iacute;as tan dif&iacute;ciles para todos y todas, y tambi&eacute;n a toda la gente que ha estado trabajando durante este a&ntilde;o para evitar que vuelva a pasar una tragedia como aquella&rdquo;, reza el comunicado.<\/p>\n","protected":false},"excerpt":{"rendered":"La proximidad del aniversario del incendio forestal que desde el 13 de agosto de 2022 y durante interminables&hellip;","protected":false},"author":2,"featured_media":24134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[594],"tags":[],"poblacion":[],"class_list":["post-43786","post","type-post","status-publish","format-standard","has-post-thumbnail","category-societat","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios\" \/>\n<meta property=\"og:description\" content=\"La proximidad del aniversario del incendio forestal que desde el 13 de agosto de 2022 y durante interminables&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-09T17:27:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T09:01:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2025\/02\/f3148489585bb79a733ccf32b2b548b3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"687\" \/>\n\t<meta property=\"og:image:height\" content=\"485\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\"},\"headline\":\"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios\",\"datePublished\":\"2023-08-09T17:27:56+00:00\",\"dateModified\":\"2025-02-25T09:01:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/\"},\"wordCount\":589,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/f3148489585bb79a733ccf32b2b548b3.jpg\",\"articleSection\":[\"Societat\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/\",\"name\":\"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/f3148489585bb79a733ccf32b2b548b3.jpg\",\"datePublished\":\"2023-08-09T17:27:56+00:00\",\"dateModified\":\"2025-02-25T09:01:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/f3148489585bb79a733ccf32b2b548b3.jpg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/f3148489585bb79a733ccf32b2b548b3.jpg\",\"width\":687,\"height\":485},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/","og_locale":"en_US","og_type":"article","og_title":"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios","og_description":"La proximidad del aniversario del incendio forestal que desde el 13 de agosto de 2022 y durante interminables&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2023-08-09T17:27:56+00:00","article_modified_time":"2025-02-25T09:01:22+00:00","og_image":[{"width":687,"height":485,"url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/f3148489585bb79a733ccf32b2b548b3.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Alex","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/"},"author":{"name":"Alex","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d"},"headline":"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios","datePublished":"2023-08-09T17:27:56+00:00","dateModified":"2025-02-25T09:01:22+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/"},"wordCount":589,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/f3148489585bb79a733ccf32b2b548b3.jpg","articleSection":["Societat"],"inLanguage":"va-ES","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/","url":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/","name":"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/f3148489585bb79a733ccf32b2b548b3.jpg","datePublished":"2023-08-09T17:27:56+00:00","dateModified":"2025-02-25T09:01:22+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/f3148489585bb79a733ccf32b2b548b3.jpg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/f3148489585bb79a733ccf32b2b548b3.jpg","width":687,"height":485},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/pego-georreferencia-la-red-de-hidrantes-del-trmino-municipal-como-medida-de-prevencin-antiincendios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"Pego georreferencia la red de hidrantes del t\u00e9rmino municipal como medida de prevenci\u00f3n antiincendios"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/canfali.com\/ca-es\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/43786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=43786"}],"version-history":[{"count":0,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/43786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/24134"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=43786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=43786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=43786"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/poblacion?post=43786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}