{"id":43781,"date":"2023-07-20T13:34:19","date_gmt":"2023-07-20T11:34:19","guid":{"rendered":"https:\/\/canfali.com\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/"},"modified":"2025-02-25T10:01:15","modified_gmt":"2025-02-25T09:01:15","slug":"profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/","title":{"rendered":"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor"},"content":{"rendered":"<p><strong>&nbsp;Especialistes del Servei d&#39;Urg&egrave;ncies subratllen les import&agrave;ncia de beure, malgrat no sentir set, aix&iacute; com evitar exposici&oacute; al sol en les hores centrals del dia<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El Cap del Servei d&#39;Urg&egrave;ncies de l&#39;Hospital de D&eacute;nia, Dr. Antonio Barcel&oacute;, destaca la import&agrave;ncia d&#39;una correcta hidrataci&oacute; per a evitar colps de calor i protegir la salut de la poblaci&oacute; davant l&#39;onada de calor que aquests dies assota la prov&iacute;ncia d&#39;Alacant, amb temperatures superiors als 40 graus en diverses &agrave;rees i m&agrave;ximes de 42 graus en alguns municipis.<\/p>\n<p>Encara que s&#39;espera que aquesta calor extrema remeta en els pr&ograve;xims dies, els professionals del Servei d&#39;Urg&egrave;ncies de l&#39;Hospital de D&eacute;nia, conscients dels riscos que les altes temperatures i l&#39;exposici&oacute; al sol poden representar per a la salut, ofereixen una s&egrave;rie de recomanacions per a gaudir de l&#39;estiu i les vacances de manera segura i responsable.<\/p>\n<p>El Dr. Barcel&oacute; posa l&#39;accent en la import&agrave;ncia de la hidrataci&oacute;, fins i tot sense sentir set, aix&iacute; com evitar el consum excessiu de begudes amb cafe&iuml;na, alcohol o refrescos. &ldquo;Hem de procurar, assegura, romandre en llocs frescos, a l&#39;ombra o amb aire condicionat, i evitar l&#39;exposici&oacute; solar i la pr&agrave;ctica d&#39;esports a l&#39;aire lliure durant les hores centrals del dia, entre les 11.00 i les 17.00 hores. A m&eacute;s, matisa, &eacute;s important utilitzar roba lleugera i de colors clars que permeta una adequada transpiraci&oacute;&quot;.<\/p>\n<p>Els professionals del Servei d&#39;Urg&egrave;ncies tamb&eacute; destaquen la import&agrave;ncia de prendre precaucions en enfrontar-se a les altes temperatures. Encara que el nostre cos t&eacute; la capacitat d&#39;autoregular-se i adaptar-se als canvis clim&agrave;tics, l&#39;exposici&oacute; a una calor excessiva o la pres&egrave;ncia de factors de risc, poden afectar el funcionament adequat de l&#39;organisme. Per tant, &eacute;s fonamental prendre mesures preventives per a garantir el seu bon estat de salut.<\/p>\n<p>&quot;Les malalties associades a la calor van des d&#39;enrampades, que poden ser un indicador primerenc que alguna cosa no va b&eacute; en el nostre cos, fins a afeccions m&eacute;s greus, com a marejos, augment de la temperatura corporal amb febre, p&egrave;rdua sobtada de consci&egrave;ncia o colps de calor&quot;, adverteixen els especialistes.<\/p>\n<p>Aquestes condicions poden afectar persones joves que realitzen exercici intens en les hores centrals del dia i no s&#39;hidraten adequadament, aix&iacute; com a xiquets, ancians i aquells que prenen uns certs medicaments, com a di&uuml;r&egrave;tics o antidepressius, que dificulten els mecanismes reguladors del cos. Factors de risc com l&#39;obesitat, la diabetis i problemes card&iacute;acs o renals tamb&eacute; dificulten la capacitat del nostre organisme per a regular la temperatura corporal.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp;Especialistes del Servei d&#39;Urg&egrave;ncies subratllen les import&agrave;ncia de beure, malgrat no sentir set, aix&iacute; com evitar exposici&oacute; al&hellip;","protected":false},"author":2,"featured_media":24119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[594],"tags":[],"poblacion":[],"class_list":["post-43781","post","type-post","status-publish","format-standard","has-post-thumbnail","category-societat","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor\" \/>\n<meta property=\"og:description\" content=\"&nbsp;Especialistes del Servei d&#039;Urg&egrave;ncies subratllen les import&agrave;ncia de beure, malgrat no sentir set, aix&iacute; com evitar exposici&oacute; al&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T11:34:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T09:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2025\/02\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\"},\"headline\":\"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor\",\"datePublished\":\"2023-07-20T11:34:19+00:00\",\"dateModified\":\"2025-02-25T09:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/\"},\"wordCount\":527,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg\",\"articleSection\":[\"Societat\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/\",\"name\":\"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg\",\"datePublished\":\"2023-07-20T11:34:19+00:00\",\"dateModified\":\"2025-02-25T09:01:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/","og_locale":"en_US","og_type":"article","og_title":"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor","og_description":"&nbsp;Especialistes del Servei d&#39;Urg&egrave;ncies subratllen les import&agrave;ncia de beure, malgrat no sentir set, aix&iacute; com evitar exposici&oacute; al&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2023-07-20T11:34:19+00:00","article_modified_time":"2025-02-25T09:01:15+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Alex","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/"},"author":{"name":"Alex","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d"},"headline":"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor","datePublished":"2023-07-20T11:34:19+00:00","dateModified":"2025-02-25T09:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/"},"wordCount":527,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg","articleSection":["Societat"],"inLanguage":"va-ES","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/","url":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/","name":"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg","datePublished":"2023-07-20T11:34:19+00:00","dateModified":"2025-02-25T09:01:15+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/d14554cb17d7c2ecb6cc3a17312fbbad.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/profesionales-del-departamento-de-salud-de-dnia-recomiendan-una-buena-hidratacin-para-prevenir-golpes-de-calor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"Professionals del Departament de Salut de D\u00e9nia recomanen una bona hidrataci\u00f3 per a previndre colps de calor"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/canfali.com\/ca-es\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/43781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=43781"}],"version-history":[{"count":0,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/43781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/24119"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=43781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=43781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=43781"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/poblacion?post=43781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}