{"id":43747,"date":"2023-05-20T15:20:47","date_gmt":"2023-05-20T13:20:47","guid":{"rendered":"https:\/\/canfali.com\/630\/"},"modified":"2025-02-25T10:00:20","modified_gmt":"2025-02-25T09:00:20","slug":"630","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/630\/","title":{"rendered":"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles"},"content":{"rendered":"<p>Una joya a pie de playa con un trato personal y familiar<\/p>\n<p>&nbsp;<\/p>\n<p>Antonio Sell&eacute;s y Maruja Mart&iacute;nez alquilaron en 1966 el hotel que &eacute;l dirig&iacute;a<\/p>\n<p>&nbsp;<\/p>\n<p>El programa con el que Els Magazinos homenajea a las familias con tradici&oacute;n hostelera, esas que han contribuido a hacer de la Marina Alta un lugar donde saborear y empaparse de lo mejor del Mediterr&aacute;neo, llega este mes de mayo al Hotel Los &Aacute;ngeles. Situado en Les Bovetes, a pie de playa, es un establecimiento de referencia y un espacio donde disfrutar y desconectar. Pero sobre todo, un lugar donde sentirse a gusto y gozar del sol, la playa, la buena mesa y la familiaridad con la que se trata a los hu&eacute;spedes. La atenci&oacute;n y el trato personal&nbsp; se han convertido en sello de la casa, car&aacute;cter que ha sabido imprimir al hotel la familia Sell&eacute;s Mart&iacute;nez y el equipo humano del que siempre se ha rodeado.&nbsp;<\/p>\n<p>Casa Meua &eacute;s Casa Teua hace este mes un homenaje a tres generaciones de una familia que ha trabajado duro para convertir el hotel en un referente, modernizando sus instalaciones y tratando de adaptarse desde el primer d&iacute;a a los cambios en la demanda y a las necesidades y exigencias de los clientes. Quienes la conocen, saben que la suya es una historia de obras y reformas -casi constantes pero necesarias- para seguir estando ah&iacute;, en lo m&aacute;s alto, en una ciudad donde la oferta hotelera no es precisamente lo m&aacute;s destacado. Ellos han sabido fidelizar al cliente con ese trato humano que te hace sentir como en casa, con una atenci&oacute;n y servicios elogiables y con una cocina que, sin dejar de lado la tradici&oacute;n, se atreve con innovaciones. Un ejemplo lo tenemos en la cena del jueves 25, con la reinterpretaci&oacute;n del figatell de rabo de toro y platos que se salen de lo cl&aacute;sico, como el capuccino de setas.<\/p>\n<p>Antonio Sell&eacute;s y Maruja Mart&iacute;nez alquilaron el Hotel Los &Aacute;ngeles en 1966, al poco de casarse. Ella, como recuerda, no sab&iacute;a nada de hoteles. Se hab&iacute;an conocido en Benidorm, a donde Antonio march&oacute; para trabajar en la conserjer&iacute;a del Hotel Planesia que, regentado por Vicente Alemany, fue uno de los establecimientos pioneros del Benidorm tur&iacute;stico. Sus conocimientos de alem&aacute;n -&ldquo;ten&iacute;a mucha facilidad para los idiomas&rdquo;, recuerda su viuda- le facilitaron el ascenso y le abrieron nuevas puertas a nivel profesional en aquel pueblo de pescadores, muy distinto al Benidorm que ahora conocemos. Trabajar&iacute;a despu&eacute;s en el Hotel Europa, con una clientela formada b&aacute;sicamente por alemanes.&nbsp;<\/p>\n<p>Una joven Maruja Mart&iacute;nez, nacida en Mutxamel, resid&iacute;a por aquellos d&iacute;as en Benidorm con su hermana. Fue a trav&eacute;s de su cu&ntilde;ado como conoci&oacute; al que ser&iacute;a su marido y con quien formar&iacute;a una familia en D&eacute;nia. All&iacute;, en su ciudad natal, Antonio dirigir&iacute;a a partir de 1965 el Hotel los &Aacute;ngeles, un hotel de playa construido pr&aacute;cticamente en medio de la nada -la carretera de Les Marines llegaba hasta all&iacute; a duras penas- que hab&iacute;a abierto sus puertas en 1961.&nbsp;<\/p>\n<p>El propietario del hotel era Francisco Estrela, natural de Madrid, que compr&oacute; la parcela donde se ubicar&iacute;a y otros terrenos en los alrededores, en su mayor parte poblados de vi&ntilde;edos. &ldquo;Un visionario&rdquo; para los tiempos que corr&iacute;an -como ella dice- en una D&eacute;nia que empezaba a hacer gui&ntilde;os al turismo.&nbsp;<\/p>\n<p>La pareja se casar&iacute;a en febrero de 1966 y en marzo de ese mismo a&ntilde;o alquilar&iacute;a el hotel. Maruja Mart&iacute;nez recuerda que no hab&iacute;a agua caliente -&ldquo;lo primero que hicimos fue ponerla&rdquo;- y que el agua de lluvia se colaba por las ventanas porque no cerraban bien.&nbsp;<\/p>\n<p>El hotel ten&iacute;a 59 habitaciones (81 en la actualidad), ofrec&iacute;a pensi&oacute;n completa y la costumbre era abrir desde junio hasta mediados de septiembre. Al poco tiempo, ampliaron la temporada con la Semana Santa, ya que hab&iacute;a familias que lo demandaban. Pasados los a&ntilde;os, se convertir&iacute;an en clientes fijos. &ldquo;Ya entonces&rdquo;, explica Cristina Sell&eacute;s, la hija del matrimonio que ejerce ahora como directora, &ldquo;se personalizaba mucho lo que el cliente quer&iacute;a, algo que nos diferencia de las cadenas hoteleras&rdquo;.&nbsp;<\/p>\n<p>En el hotel se daban banquetes y bodas. Poco a poco se convirti&oacute; en testigo del espectacular crecimiento que experimentaba D&eacute;nia y, en especial, la zona de Les Marines. Tambi&eacute;n en protagonista, porque se fue ganando un nombre y cosechando una clientela fiel. Antonio Sell&eacute;s, relata su esposa, jug&oacute; un importante papel tambi&eacute;n en la prolongaci&oacute;n de la carretera hasta el Molinell, para lo que se promovi&oacute; incluso una recogida de firmas.&nbsp;<\/p>\n<p>El matrimonio Sell&eacute;s Mart&iacute;nez comprar&iacute;a el hotel en 1982. Desde el primer momento, supo que la atenci&oacute;n y la calidad en el servicio eran fundamentales. Y para garantizarlas se hizo necesario emprender varias reformas. Una de ellas, en la d&eacute;cada de los 80, fue el cambio de ubicaci&oacute;n de la cocina. Las necesidades de los clientes eran otras y se suprimi&oacute; la pensi&oacute;n completa, manteniendo la media pensi&oacute;n y ampliando poco a poco el servicio de restaurante, que pas&oacute;, c&oacute;mo no, por una etapa de platos combinados.<\/p>\n<p>La reforma m&aacute;s importante se acometi&oacute; en 1995, cuando se dejaron las dos plantas del hotel di&aacute;fanas para remodelar las habitaciones y se dotaron de terraza las que tienen vistas al Montg&oacute;. A diferencia de lo que puedan creer algunos, &ldquo;el hotel no ha sido la gallina de los huevos de oro&rdquo; &#8211; apunta Maruja Mart&iacute;nez- &ldquo;y todo lo que se ha sacado se ha vuelto a invertir en &eacute;l&rdquo;.&nbsp;<\/p>\n<p>En 1998 se instalan los ascensores, se reforma el hall y la planta baja; en 2003 se construyen los &aacute;ticos de la tercera planta y el anexo de 8 habitaciones; en 2006 la piscina; en 2011, nuevas habitaciones, el gimnasio y el spa. Son tal vez las reformas m&aacute;s destacadas de un hotel que est&aacute; en constante evoluci&oacute;n y que mantuvo las dos estrellas hasta el a&ntilde;o 2000, cuando lleg&oacute; la tercera. La cuarta lo har&iacute;a en 2011, cuando se estim&oacute; necesario subir de categor&iacute;a porque as&iacute; lo exig&iacute;a la demanda, &ldquo;aunque mi padre prefer&iacute;a que fuese el mejor hotel de tres estrellas a tener cuatro&rdquo;, explica Cristina.<\/p>\n<p>El tipo de clientes no ha cambiado tanto como la duraci&oacute;n de las estancias. Al principio julio era el mes de los francese; a los ingleses y alemanes no se les ve&iacute;a por all&iacute;. Ahora, la primavera y el oto&ntilde;o son temporadas de turistas extranjeros. El verano, como entonces, se llena sobre todo de familias espa&ntilde;olas, valencianas y madrile&ntilde;as m&aacute;s que nada. Las restricciones por el covid que solo permitieron viajar dentro de cada comunidad favorecieron la llegada de clientes de la provincia de Alicante, una tendencia que ha ido al alza con la implantaci&oacute;n del bono tur&iacute;stico. Aunque se sale m&aacute;s, las estancias son m&aacute;s cortas y las reservas se hacen a &uacute;ltima hora.&nbsp;<\/p>\n<p>Cristina (directora del hotel), Ana (responsable de recursos humanos y de la elaboraci&oacute;n y traducci&oacute;n de las cartas) y Tono (director de compras, sumiller y encargado de la carta de vinos) han vinculado su vida a la empresa familiar, en la que han pasado por diferentes puestos. &ldquo;Todos empezamos carreras universitarias y compaginamos los estudios con el trabajo&rdquo;, indica Ana, &ldquo;pero los tres optamos por quedarnos en el hotel&rdquo;.&nbsp;<\/p>\n<p>Ahora, el hotel cierra durante tres o cuatro meses en invierno, los de mayor humedad, tiempo que como se&ntilde;ala Tono se aprovecha para realizar labores de mantenimiento, siempre necesarias por su proximidad al mar.<\/p>\n<p>Antonio Sell&eacute;s estar&iacute;a muy contento de ver que sus nietos Carmen, Cristina, Santiago y Arturo -la tercera generaci&oacute;n- se han formado para ello y se han implicado tambi&eacute;n en el negocio, apostando por aspectos como la sostenibilidad, la innovaci&oacute;n y la tecnolog&iacute;a.&nbsp;<\/p>\n<p>Orgullosos de la labor que han hecho padres y abuelos, presumen de las buenas valoraciones que obtiene el hotel en recursos humanos, trato familiar y limpieza. Una medalla esta &uacute;ltima que atribuyen a Maruja Mart&iacute;nez, &ldquo;que ha ense&ntilde;ado muy bien a las gobernantas y un aspecto que siempre se ha encargado de controlar personalmente&rdquo;.&nbsp;<\/p>\n<p>De la mano de Cervezas Turia, Els Magazinos lleva el jueves el programa Casa Meua &eacute;s Casa Teua a esta peque&ntilde;a joya de Les Bovetes para recibir el verano. Bienvenido sea.<\/p>\n<p>&nbsp;<\/p>\n<p>El men&uacute; de la cena del jueves 25 de mayo, a les 21 h., en el Hotel Los &Aacute;ngeles: Cocktail de bienvenida: Tomate, queso y sardina; Patata, yema y sobrasada; Bacaladilla, coliflor y allioli; Croquetas de pollo; Almendras. En mesa: Capuccino de setas; Corvina, suquet, chalota y espinacas; Figatells de rabo de toro, parmentier y piparras; Postre: Sorbete de c&iacute;tricos de nuestra huerta; Trufas caseras &amp; Caf&eacute; e infusiones. Maridaje: Cervezas Turia e Inedit con dos de los platos, y adem&aacute;s vino Vilerma blanco, Mestizaje tinto y Cava Paloma M&iacute;nguez. Precio: 50 euros. Reservas: 96 578 04 58<\/p>\n","protected":false},"excerpt":{"rendered":"Una joya a pie de playa con un trato personal y familiar &nbsp; Antonio Sell&eacute;s y Maruja Mart&iacute;nez&hellip;","protected":false},"author":2,"featured_media":24011,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[594],"tags":[],"poblacion":[],"class_list":["post-43747","post","type-post","status-publish","format-standard","has-post-thumbnail","category-societat","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/630\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles\" \/>\n<meta property=\"og:description\" content=\"Una joya a pie de playa con un trato personal y familiar &nbsp; Antonio Sell&eacute;s y Maruja Mart&iacute;nez&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/630\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-20T13:20:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T09:00:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2025\/02\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1059\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\"},\"headline\":\"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles\",\"datePublished\":\"2023-05-20T13:20:47+00:00\",\"dateModified\":\"2025-02-25T09:00:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/\"},\"wordCount\":1730,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg\",\"articleSection\":[\"Societat\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/\",\"name\":\"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg\",\"datePublished\":\"2023-05-20T13:20:47+00:00\",\"dateModified\":\"2025-02-25T09:00:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg\",\"width\":1600,\"height\":1059},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/630\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/630\/","og_locale":"en_US","og_type":"article","og_title":"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles","og_description":"Una joya a pie de playa con un trato personal y familiar &nbsp; Antonio Sell&eacute;s y Maruja Mart&iacute;nez&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/630\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2023-05-20T13:20:47+00:00","article_modified_time":"2025-02-25T09:00:20+00:00","og_image":[{"width":1600,"height":1059,"url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Alex","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/630\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/630\/"},"author":{"name":"Alex","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d"},"headline":"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles","datePublished":"2023-05-20T13:20:47+00:00","dateModified":"2025-02-25T09:00:20+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/630\/"},"wordCount":1730,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/630\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg","articleSection":["Societat"],"inLanguage":"va-ES","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/630\/","url":"https:\/\/canfali.com\/ca-es\/630\/","name":"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/630\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/630\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg","datePublished":"2023-05-20T13:20:47+00:00","dateModified":"2025-02-25T09:00:20+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/630\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/630\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/630\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/0bb3869adc26a27ae52fa7d55e4ecffb.jpg","width":1600,"height":1059},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/630\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"A las puertas del verano, Casa Meua \u00e9s Casa Teua llega al Hotel Los \u00c1ngeles"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/canfali.com\/ca-es\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/43747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=43747"}],"version-history":[{"count":0,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/43747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/24011"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=43747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=43747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=43747"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/poblacion?post=43747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}