{"id":42364,"date":"2023-06-09T15:16:02","date_gmt":"2023-06-09T13:16:02","guid":{"rendered":"https:\/\/canfali.com\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/"},"modified":"2025-02-25T12:22:45","modified_gmt":"2025-02-25T11:22:45","slug":"el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/","title":{"rendered":"El Hospital de D\u00e9nia acoge &#8220;Del Negro al Rojo&#8221;, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero"},"content":{"rendered":"<p>&nbsp;El Hospital de D&eacute;nia, del Grupo sanitario Ribera, a trav&eacute;s de la iniciativa cuidArt, acoge la colecci&oacute;n personal del Dr. Mariano Guerrero, &quot;Del Negro al Rojo&quot;; una muestra que recoge una cuidada selecci&oacute;n de piezas de la Colecci&oacute;n Toguna que, por primera vez, se expone al p&uacute;blico.<\/p>\n<p>En el acto de inauguraci&oacute;n que, se ha celebrado este mediod&iacute;a en el centro sanitario dianense, han estado presentes el Presidente y la Consejera Delegada del Grupo sanitario Ribera, Alberto de Rosa y Elisa Tarazona, respectivamente; el Director Gerente del Departamento de Salud de D&eacute;nia, Javier Palau; la Directora de cuidArt, Alicia Ventura, y el propio Dr. Mariano Guerrero.<\/p>\n<p>Se trata de la colecci&oacute;n privada de un profesional sanitario, en la que se vuelve a establecer una nueva conexi&oacute;n entre el mundo m&eacute;dico y el art&iacute;stico, lo que permite disfrutar de estas magn&iacute;ficas piezas en los espacios del Hospital de D&eacute;nia.&nbsp;<\/p>\n<p>Para el Dr. Mariano Guerrero &quot;los miembros de la llamada vanguardia espa&ntilde;ola son los que llevan a cabo una sobresaliente contribuci&oacute;n al arte moderno espa&ntilde;ol del siglo XX, con la apuesta decidida por la obra gr&aacute;fica como expresi&oacute;n art&iacute;stica de refinada elegancia, alejados del concepto de prueba, del tama&ntilde;o reducido y del negro monocolor. Son relevantes las aportaciones al mundo del papel grafiado, como arte may&uacute;sculo, por parte de los componentes del grupo Dau al Set, de la Escuela de Altamira, de El Paso, del grupo de Cuenca y de todas las &uacute;ltimas generaciones de final del siglo XX&quot;.<\/p>\n<p>Precisamente &quot;Del Negro al Rojo&quot; recoge gran parte de la obra gr&aacute;fica de destacados representantes de la Abstracci&oacute;n de la cita Vanguardia espa&ntilde;ola, entre los a&ntilde;os 60-80 del siglo XX, como Jos&eacute; Guerrero, Tapies, Saura, Chillida, Clav&eacute;, Arroyo, Broto o Usl&eacute;.<\/p>\n<p>Para el Dr. Guerrero &quot;esta exposici&oacute;n solo pretende ser una pincelada, una humilde r&aacute;faga, dentro del emocionante universo que, sobre papel, han construido las vanguardias pict&oacute;ricas espa&ntilde;olas del siglo XX, para deleite sensorial, utilizando el negro y el rojo como estela conductora que fusiona las obras de los diferentes artistas que componen la muestra&quot;.<\/p>\n<p>El negro es un homenaje a lo cl&aacute;sico, a los maestros, a lo est&aacute;tico, a lo inerte; y el rojo, como rey de la escala crom&aacute;tica, es s&iacute;mbolo del atrevimiento, de la pasi&oacute;n y de la sangre.<\/p>\n<p>&quot;Cuando el artista combina el sereno y elegante negro con el atrevido rojo, entre los dos colores se establece una excitante relaci&oacute;n que conmueve y que puede simbolizar las dos caras de la vida&quot;, subraya Guerrero.<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp;El Hospital de D&eacute;nia, del Grupo sanitario Ribera, a trav&eacute;s de la iniciativa cuidArt, acoge la colecci&oacute;n personal&hellip;","protected":false},"author":2,"featured_media":29452,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[597],"tags":[],"poblacion":[],"class_list":["post-42364","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-ca-es","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>El Hospital de D\u00e9nia acoge &quot;Del Negro al Rojo&quot;, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Hospital de D\u00e9nia acoge &quot;Del Negro al Rojo&quot;, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero\" \/>\n<meta property=\"og:description\" content=\"&nbsp;El Hospital de D&eacute;nia, del Grupo sanitario Ribera, a trav&eacute;s de la iniciativa cuidArt, acoge la colecci&oacute;n personal&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-09T13:16:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T11:22:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2025\/02\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\"},\"headline\":\"El Hospital de D\u00e9nia acoge &#8220;Del Negro al Rojo&#8221;, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero\",\"datePublished\":\"2023-06-09T13:16:02+00:00\",\"dateModified\":\"2025-02-25T11:22:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/\"},\"wordCount\":525,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/\",\"name\":\"El Hospital de D\u00e9nia acoge \\\"Del Negro al Rojo\\\", la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg\",\"datePublished\":\"2023-06-09T13:16:02+00:00\",\"dateModified\":\"2025-02-25T11:22:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg\",\"width\":2000,\"height\":1333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Hospital de D\u00e9nia acoge \u00abDel Negro al Rojo\u00bb, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"El Hospital de D\u00e9nia acoge \"Del Negro al Rojo\", la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/","og_locale":"en_US","og_type":"article","og_title":"El Hospital de D\u00e9nia acoge \"Del Negro al Rojo\", la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero","og_description":"&nbsp;El Hospital de D&eacute;nia, del Grupo sanitario Ribera, a trav&eacute;s de la iniciativa cuidArt, acoge la colecci&oacute;n personal&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2023-06-09T13:16:02+00:00","article_modified_time":"2025-02-25T11:22:45+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Alex","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/"},"author":{"name":"Alex","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d"},"headline":"El Hospital de D\u00e9nia acoge &#8220;Del Negro al Rojo&#8221;, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero","datePublished":"2023-06-09T13:16:02+00:00","dateModified":"2025-02-25T11:22:45+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/"},"wordCount":525,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg","articleSection":["Cultura"],"inLanguage":"va-ES","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/","url":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/","name":"El Hospital de D\u00e9nia acoge \"Del Negro al Rojo\", la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg","datePublished":"2023-06-09T13:16:02+00:00","dateModified":"2025-02-25T11:22:45+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/a1ecd100e0e2ff55d7f30c8d4a650575.jpg","width":2000,"height":1333},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/el-hospital-de-dnia-acoge-del-negro-al-rojo-la-coleccin-personal-indita-del-dr-mariano-guerrero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"El Hospital de D\u00e9nia acoge \u00abDel Negro al Rojo\u00bb, la colecci\u00f3n personal in\u00e9dita del Dr. Mariano Guerrero"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/canfali.com\/ca-es\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/42364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=42364"}],"version-history":[{"count":0,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/42364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/29452"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=42364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=42364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=42364"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/poblacion?post=42364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}