{"id":42363,"date":"2023-06-08T17:50:14","date_gmt":"2023-06-08T15:50:14","guid":{"rendered":"https:\/\/canfali.com\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/"},"modified":"2025-02-25T12:22:43","modified_gmt":"2025-02-25T11:22:43","slug":"el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/","title":{"rendered":"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent"},"content":{"rendered":"<p>Les obres d&rsquo;adequaci&oacute; de la pla&ccedil;a de bous d&rsquo;Ondara a les actuals normatives per a aprofitar-la com espai polivalent han arrancat aquesta setmana amb els treballs de protecci&oacute; contra incendis que han comportat la &nbsp;instal&middot;laci&oacute; d&rsquo;un sistema de protecci&oacute; contra incendis, format per boques d&rsquo;incendi per a extinci&oacute; per aigua.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;EN COMPLIMENT DE L&rsquo;ACTUAL NORMATIVA&rdquo;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aquesta actuaci&oacute;, quantificada en 44.207,35 euros + IVA, ha estat supervisada pel regidor de Manteniment en funcions, Miguel Gomis, qui l&rsquo;ha emmarcada dins dels requisits de la &nbsp;normativa actual per a la realitzaci&oacute; d&rsquo;esdeveniments de p&uacute;blica concurr&egrave;ncia, incloent, a partir d&rsquo;enguany i per primera vegada, els actes taurins tamb&eacute;. En concret, aquest sistema de protecci&oacute; contra incendis s&rsquo;instal&middot;lar&agrave; per tot el cos taur&iacute;, amb l&rsquo;estesa de canonada d&rsquo;abastiment, l&rsquo;habilitaci&oacute; de quatre boques d&rsquo;incendi i la disposici&oacute; d&#39;un quart tancat per a la instal&middot;laci&oacute; del quadre de control, de les bombes i un dip&ograve;sit de subministrament d&rsquo;aigua de 12 m3.<\/p>\n<p>Aix&iacute; mateix, Gomis ha explicat que formen part del projecte que permetr&agrave; l&#39;homologaci&oacute; de la pla&ccedil;a de bous per a diferents usos de forma permanent; de manera que puga albergar qualsevol tipus d&#39;actuaci&oacute; o esdeveniment sense haver de gestionar altres expedients d&#39;activitats extraordin&agrave;ries. A banda, el regidor ha detallat que l&rsquo;Ajuntament a comen&ccedil;ar ja fa un temps el proc&eacute;s per a poder habilitar l&#39;edifici per a l&#39;&uacute;s polivalent amb el compliment de les diferents normatives actuals, atesa la seua antiguitat, i que va comen&ccedil;ar amb la contractaci&oacute; dels serveis t&egrave;cnics per a la redacci&oacute; del projecte d&#39;activitat per a dit &uacute;s<\/p>\n<p>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Les obres d&rsquo;adequaci&oacute; de la pla&ccedil;a de bous d&rsquo;Ondara a les actuals normatives per a aprofitar-la com espai&hellip;","protected":false},"author":2,"featured_media":29449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[597],"tags":[],"poblacion":[],"class_list":["post-42363","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-ca-es","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent\" \/>\n<meta property=\"og:description\" content=\"Les obres d&rsquo;adequaci&oacute; de la pla&ccedil;a de bous d&rsquo;Ondara a les actuals normatives per a aprofitar-la com espai&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-08T15:50:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T11:22:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2025\/02\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\"},\"headline\":\"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent\",\"datePublished\":\"2023-06-08T15:50:14+00:00\",\"dateModified\":\"2025-02-25T11:22:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/\"},\"wordCount\":372,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/\",\"name\":\"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg\",\"datePublished\":\"2023-06-08T15:50:14+00:00\",\"dateModified\":\"2025-02-25T11:22:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/","og_locale":"en_US","og_type":"article","og_title":"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent","og_description":"Les obres d&rsquo;adequaci&oacute; de la pla&ccedil;a de bous d&rsquo;Ondara a les actuals normatives per a aprofitar-la com espai&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2023-06-08T15:50:14+00:00","article_modified_time":"2025-02-25T11:22:43+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Alex","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/"},"author":{"name":"Alex","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d"},"headline":"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent","datePublished":"2023-06-08T15:50:14+00:00","dateModified":"2025-02-25T11:22:43+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/"},"wordCount":372,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg","articleSection":["Cultura"],"inLanguage":"va-ES","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/","url":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/","name":"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg","datePublished":"2023-06-08T15:50:14+00:00","dateModified":"2025-02-25T11:22:43+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/3a2178c0624d9aec3d0adf2c9238fd4b.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/el-auntamiento-de-ondara-pone-en-marcha-un-proecto-para-reconvertir-la-plaza-de-toros-como-espacio-polivalente-permanente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"L\u2019Ajuntament d\u2019Ondara engega un projecte per a reconvertir la pla\u00e7a de bous com a espai polivalent permanent"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/canfali.com\/ca-es\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/42363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=42363"}],"version-history":[{"count":0,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/42363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/29449"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=42363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=42363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=42363"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/poblacion?post=42363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}