{"id":42361,"date":"2023-06-08T15:50:40","date_gmt":"2023-06-08T13:50:40","guid":{"rendered":"https:\/\/canfali.com\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/"},"modified":"2025-02-25T12:22:40","modified_gmt":"2025-02-25T11:22:40","slug":"de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/","title":{"rendered":"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>Abraham Cupeiro, Pep Gimeno &lsquo;Botifarra&rsquo;, Depedro, Rosario &lsquo;La Tremendita&rsquo; i la Colleta del Verger, en el cartell del festival<\/strong><\/p>\n<p>La Regidoria de Cultura de l&rsquo;Ajuntament de D&eacute;nia ha fet p&uacute;blic el programa del XXXI Festival M&uacute;sica al Castell. Cinc actuacions donen cos enguany a un festival que s&rsquo;ha convertit en punt de trobada d&rsquo;artistes que entenen de diferents maneres la m&uacute;sica d&rsquo;arrel. Sense faltar al tret d&rsquo;identitat d&rsquo;un festival amb &agrave;nima mediterr&agrave;nia, el programa ens convida a fer un recorregut de nord a sud de la pen&iacute;nsula amb la m&uacute;sica tradicional. Des de Gal&iacute;cia a Sevilla, fent parada a X&agrave;tiva i Madrid, el cartell reuneix quatre maneres d&rsquo;entendre la m&uacute;sica que van m&eacute;s enll&agrave; del cant popular i s&rsquo;endinsen en la recerca i la investigaci&oacute;. Com a colof&oacute;, i amb la intenci&oacute; de recuperar el patrimoni musical de la Marina Alta, s&rsquo;ha programat l&rsquo;actuaci&oacute; d&rsquo;una colla, en este cas la del Verger.<\/p>\n<p>M&uacute;sica al Castell se celebrar&agrave; entre el 26 i el 30 de juliol i comptar&agrave; amb les actuacions d&rsquo;Abraham Cupeiro i l&rsquo;ensemble Vent a Cinc Septet de Ll&iacute;ria; Pep Gimeno Botifarra acompanyat entre altres pel guitarrista denier Miquel P&eacute;rez Perell&oacute;, que ha manifestat la seua il&middot;lusi&oacute; d&rsquo;actuar en l&rsquo;esplanada del castell; el cantant i m&uacute;sic Depedro; la cantaora Rosario &lsquo;La Tremendita&rsquo;; i la Colleta del Verger.<\/p>\n<p>Totes les actuacions, excepte la de la colla, tindran lloc dalt del castell, a l&rsquo;esplanada del Palau del Governador, a les 23 hores. Els percussionistes i els dol&ccedil;ainers del Verger actuaran a la Pla&ccedil;a del Consell a les 20.30 hores.&nbsp;<\/p>\n<p>El regidor de Cultura, Ra&uuml;l Garc&iacute;a de la Reina, ha qualificat el cartell d&rsquo;atractiu i ha recordat que les propostes d&rsquo;enguany se sumen a l&rsquo;ampli llistat d&rsquo;artistes que han actuat, durant m&eacute;s de tres d&egrave;cades, en els escenaris de M&uacute;sica al Castell, &ldquo;el festival valenci&agrave; m&eacute;s longeu dedicat al folk&rdquo;.<\/p>\n<p>Els concerts del castell se celebraran els dies 26, 27, 28 i 29 de juliol i tindran un aforament per a 700 espectadors. Les invitacions per als concerts gratu&iuml;ts (dies 26, 27 i 30 de juliol), aix&iacute; com les entrades per als que s&oacute;n de pagament (dies 28 i 29 de juliol) estaran disponibles a partir del 15 de juny en la plataforma Notikumi.com.<\/p>\n<p><strong>LES ACTUACIONS<\/strong><\/p>\n<p>El luthier i multiinstrumentista Abraham Cupeiro torna a D&eacute;nia -despr&eacute;s d&rsquo;actuar amb l&rsquo;Agrupaci&oacute; Art&iacute;stica Musical l&rsquo;estiu passat- per proposar-nos un viatge en el temps amb l&rsquo;espectacle Os Sons Esquecidos (Els sons oblidats), en el qual el gallec experimenta amb sons i instruments d&rsquo;altres &egrave;poques i cultures. En esta ocasi&oacute;, Cupeiro estar&agrave; acompanyat el dimecres 26 de juliol per l&rsquo;ensemble Vent a Cinc Septet de Ll&iacute;ria, Ciutat Creativa de la M&uacute;sica per la UNESCO. Els seus integrants comparteixen la idea d&rsquo;acostar obres mestres de la hist&ograve;ria de la m&uacute;sica a audi&egrave;ncies m&eacute;s redu&iuml;des i pr&ograve;ximes i, en ser docents, solen incloure en la seua programaci&oacute; la interpretaci&oacute; de contes musicals amb narrador.<\/p>\n<p>Esta col&middot;laboraci&oacute; que el p&uacute;blic de M&uacute;sica al Castell tindr&agrave; oportunitat de gaudir, sorgeix del contacte i intercanvi d&rsquo;experi&egrave;ncies que Ll&iacute;ria i D&eacute;nia tenen com a membres de la xarxa de Ciutats Creatives de la UNESCO i&nbsp; de l&rsquo;Associaci&oacute; Espanyola de Ciutats Creatives de la UNESCO. Una col&middot;laboraci&oacute; que van encetar el mes de febrer passat participant amb un espectacle conjunt, que unia m&uacute;sica i gastronomia, en la tercera edici&oacute; del Festival de Arte &amp; Gastronom&iacute;a de la prov&iacute;ncia de Val&egrave;ncia FestIN.<\/p>\n<p>El dijous 27, Pep Gimeno &lsquo;Botifarra&rsquo; presentar&agrave; el seu &uacute;ltim treball Ja ve l&rsquo;aire. Es tracta d&rsquo;un disc en clau femenina en qu&egrave;, segons ha explicat Miquel P&eacute;rez Perell&oacute;, el cantaor de X&agrave;tiva fa &ldquo;un reconeixement a les dones, la major font d`informaci&oacute; en la seua tasca de recuperaci&oacute; de la mem&ograve;ria musical valenciana&rdquo;. Des que va comen&ccedil;ar la gira de concerts a gener d&rsquo;enguany al Palau de les Arts de Val&egrave;ncia, l&rsquo;espectacle ha recorregut ja diverses ciutats de dins i fora de la Comunitat Valenciana. Sobre l&rsquo;escenari, set m&uacute;sics acompanyant el &lsquo;Botifarra.&rsquo;<\/p>\n<p>El cantant i m&uacute;sic Depedro actuar&agrave; el divendres 28 en format ac&uacute;stic. El madrileny ha interpretat pels cinc continents &ldquo;la seua m&uacute;sica personal i sense fronteres&rdquo;, publicant discos en m&eacute;s de 30 pa&iuml;sos. En el concert que oferir&agrave; a D&eacute;nia interpretar&agrave; can&ccedil;ons dels seus dos &uacute;ltims treballs -M&aacute;quina de piedad i Antes de que anochezca-, les quals se sustenten en &ldquo;hist&ograve;ries amb passions universals i en ritmes d&rsquo;arrel llatinoamericana, africana, estatunidenca, mediterr&agrave;nia i transfronterera&rdquo;, ha indicat Maribel Font, t&egrave;cnica de Cultura.<\/p>\n<p>La cantaora, compositora i lletrista Rosario &ldquo;La Tremendita&rdquo; i la seua banda de flamenc experimental &ndash;amb bateria, baix, teclats, guitarra i baix el&egrave;ctric- oferiran el concert de la nit del 29 de juliol. Ha estat definida com l&rsquo;autora de l&rsquo;ultima gran revoluci&oacute; del cant flamenc, la qual &ldquo;des del domini de la tradici&oacute;, ha trencat motles i ha revolucionat el flamenc&rdquo;. Va estar nominada en 2015 i 2018 a Millor &Agrave;lbum Flamenc en els Latin Grammy Awards. En 2022, va rebre el Premi MIN de m&uacute;sica independent al Millor &Agrave;lbum de Flamenc amb Tremenda.<\/p>\n<p>Tancar&agrave; el festival el diumenge 30, a la pla&ccedil;a del Consell, La Colleta del Verger, dirigida per Pasqual Salort, &ldquo;un bon exponent de les formacions existents a la comarca que estan rescatant i actualitzant el repertori per a dol&ccedil;aines i percussi&oacute;&rdquo;, en paraules de Font.<\/p>\n<p>L&rsquo;alcalde, Vicent Grimalt, ha ressaltat la participaci&oacute; de colles en el Festival M&uacute;sica al castell en els darrers anys i ha felicitat al departament de Cultura per afavorir &ldquo;la recuperaci&oacute; de la cultura valenciana i de la comarca i donar visibilitat als m&uacute;sics de la Marina Alta en un festival consolidat com este&rdquo;, aix&iacute; com pel treball realitzar per aconseguir &ldquo;un programa tan fant&agrave;stic&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"&nbsp; Abraham Cupeiro, Pep Gimeno &lsquo;Botifarra&rsquo;, Depedro, Rosario &lsquo;La Tremendita&rsquo; i la Colleta del Verger, en el cartell&hellip;","protected":false},"author":2,"featured_media":29443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[597],"tags":[],"poblacion":[],"class_list":["post-42361","post","type-post","status-publish","format-standard","has-post-thumbnail","category-cultura-ca-es","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Abraham Cupeiro, Pep Gimeno &lsquo;Botifarra&rsquo;, Depedro, Rosario &lsquo;La Tremendita&rsquo; i la Colleta del Verger, en el cartell&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-08T13:50:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-25T11:22:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2025\/02\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Alex\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Alex\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/\"},\"author\":{\"name\":\"Alex\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\"},\"headline\":\"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel\",\"datePublished\":\"2023-06-08T13:50:40+00:00\",\"dateModified\":\"2025-02-25T11:22:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/\"},\"wordCount\":1239,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/\",\"name\":\"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg\",\"datePublished\":\"2023-06-08T13:50:40+00:00\",\"dateModified\":\"2025-02-25T11:22:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/02\\\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg\",\"width\":2560,\"height\":1696},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/25dd7e79206e119c02d489a3b67ca83d\",\"name\":\"Alex\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g\",\"caption\":\"Alex\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/alex\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/","og_locale":"en_US","og_type":"article","og_title":"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel","og_description":"&nbsp; Abraham Cupeiro, Pep Gimeno &lsquo;Botifarra&rsquo;, Depedro, Rosario &lsquo;La Tremendita&rsquo; i la Colleta del Verger, en el cartell&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2023-06-08T13:50:40+00:00","article_modified_time":"2025-02-25T11:22:40+00:00","og_image":[{"width":2560,"height":1696,"url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg","type":"image\/jpeg"}],"author":"Alex","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Alex","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/"},"author":{"name":"Alex","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d"},"headline":"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel","datePublished":"2023-06-08T13:50:40+00:00","dateModified":"2025-02-25T11:22:40+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/"},"wordCount":1239,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg","articleSection":["Cultura"],"inLanguage":"va-ES","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/","url":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/","name":"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg","datePublished":"2023-06-08T13:50:40+00:00","dateModified":"2025-02-25T11:22:40+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/02\/496eb3aef1bc673162317e90aaa87a81-scaled.jpg","width":2560,"height":1696},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/de-nord-a-sud-msica-al-castell-fa-un-recorregut-per-la-pennsula-amb-la-can-darrel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"De nord a sud: M\u00fasica al Castell fa un recorregut per la pen\u00ednsula amb la can\u00e7\u00f3 d\u2019arrel"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/25dd7e79206e119c02d489a3b67ca83d","name":"Alex","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/98bd9e8345af882c94b4d49db053494ffab4b0a9ca408823ad3dbaf04d352f02?s=96&d=mm&r=g","caption":"Alex"},"url":"https:\/\/canfali.com\/ca-es\/author\/alex\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/42361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=42361"}],"version-history":[{"count":0,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/42361\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/29443"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=42361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=42361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=42361"},{"taxonomy":"poblacion","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/poblacion?post=42361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}