{"id":105057,"date":"2026-07-15T11:20:27","date_gmt":"2026-07-15T09:20:27","guid":{"rendered":"https:\/\/canfali.com\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/"},"modified":"2026-07-15T11:23:07","modified_gmt":"2026-07-15T09:23:07","slug":"denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo","status":"publish","type":"post","link":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/","title":{"rendered":"D\u00e9nia activa l&#8217;alerta taronja per l&#8217;onada de calor i tanca els accessos al Montg\u00f3"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n<p class=\"wp-block-paragraph\">Davant l&#8217;episodi de temperatures extremes que afecta la Comunitat Valenciana, l&#8217;Ajuntament de D\u00e9nia ha activat un paquet de mesures extraordin\u00e0ries per a minimitzar els riscos derivats de la calor sufocant. Hui dimecres, s&#8217;ha decretat l&#8217;av\u00eds taronja a la prov\u00edncia d&#8217;Alacant, amb previsions que al litoral puguen arribar als 30 graus i nivells de risc elevats.<br\/><br\/>\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Una de les mesures \u00e9s el tancament al p\u00fablic del Parc Natural del Montg\u00f3, incloent-hi la Cova Tallada, Torre del Gerro, La Lloma del Castanyar, el Cam\u00ed de la Col\u00f2nia, els accessos des de la Marquesa VI pel Coll de Pus i pel carrer Medusa, aix\u00ed com les zones de La Xara en el Centre Ocupacional i Jes\u00fas Pobre. Per a garantir el compliment d&#8217;esta normativa, la Policia Local i la Policia Nacional ja mantenen un operatiu coordinat. Els dos cossos s&#8217;encarreguen de les tasques de control, vigil\u00e0ncia i, si \u00e9s procedent, identificaci\u00f3 de persones durant el per\u00edode que dur l&#8217;alerta.&#13;\n&#13;\n&#13;\n<\/p>\n\n<p class=\"wp-block-paragraph\">Paral\u00b7lelament al tancament d&#8217;espais naturals, l&#8217;Ajuntament ha mobilitzat els recursos socials i ha alertat la Creu Roja local perqu\u00e8 active de manera immediata els protocols d&#8217;assist\u00e8ncia i suport dirigits a les persones sense llar, un dels col\u00b7lectius m\u00e9s vulnerables davant les altes temperatures.&#13;\n<\/p>\n\n<p class=\"wp-block-paragraph\">Des de l&#8217;administraci\u00f3 local s&#8217;insistix a evitar qualsevol activitat a l&#8217;aire lliure entre les 12 i les 16 hores, prestant especial atenci\u00f3 als col\u00b7lectius vulnerables com la gent gran i xiquets. Aix\u00ed mateix, s&#8217;han recordat les recomanacions b\u00e0siques de la Conselleria de Sanitat i Salut P\u00fablica per a la ciutadania, que inclouen beure abundant aigua, utilitzar roba lleugera, evitar l&#8217;exposici\u00f3 directa en el sol en les hores centrals del dia, fer esport sol en les hores de menys calor, mantindre la vivenda fresca i ventilada, prioritzar el consum d&#8217;aliments lleugers com a ensalades, fruites i verdures, i utilitzar cremes protectores adequades per a protegir les persones majors i dependents.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"Davant l&#8217;episodi de temperatures extremes que afecta la Comunitat Valenciana, l&#8217;Ajuntament de D\u00e9nia ha activat un paquet de&hellip;","protected":false},"author":7,"featured_media":105055,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"csco_display_header_overlay":false,"csco_singular_sidebar":"","csco_page_header_type":"","csco_page_load_nextpost":"","csco_post_video_location":[],"csco_post_video_location_hash":"","csco_post_video_url":"","csco_post_video_bg_start_time":0,"csco_post_video_bg_end_time":0,"footnotes":""},"categories":[614],"tags":[687,3703,8459,2148],"class_list":["post-105057","post","type-post","status-publish","format-standard","has-post-thumbnail","category-municipal-ca-es","tag-denia-ca-es","tag-onada-de-calor","tag-parc-natural-del-montgo","tag-policia-local-ca-es-2","cs-entry","cs-video-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9nia activa l&#039;alerta taronja per l&#039;onada de calor i tanca els accessos al Montg\u00f3 - Canfali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9nia activa l&#039;alerta taronja per l&#039;onada de calor i tanca els accessos al Montg\u00f3\" \/>\n<meta property=\"og:description\" content=\"Davant l&#8217;episodi de temperatures extremes que afecta la Comunitat Valenciana, l&#8217;Ajuntament de D\u00e9nia ha activat un paquet de&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Canfali\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T09:20:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T09:23:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canfali.com\/app\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bolta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@canfalima\" \/>\n<meta name=\"twitter:site\" content=\"@canfalima\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bolta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/\"},\"author\":{\"name\":\"Bolta\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/9c651adc904f3c4e0243f54407751557\"},\"headline\":\"D\u00e9nia activa l&#8217;alerta taronja per l&#8217;onada de calor i tanca els accessos al Montg\u00f3\",\"datePublished\":\"2026-07-15T09:20:27+00:00\",\"dateModified\":\"2026-07-15T09:23:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/\"},\"wordCount\":355,\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg\",\"keywords\":[\"d\u00e9nia\",\"onada de calor\",\"Parc Natural del Montg\u00f3\",\"Policia Local\"],\"articleSection\":[\"Municipal\"],\"inLanguage\":\"va-ES\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/\",\"name\":\"D\u00e9nia activa l'alerta taronja per l'onada de calor i tanca els accessos al Montg\u00f3 - Canfali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg\",\"datePublished\":\"2026-07-15T09:20:27+00:00\",\"dateModified\":\"2026-07-15T09:23:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#breadcrumb\"},\"inLanguage\":\"va-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2026\\\/07\\\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9nia activa l&#8217;alerta taronja per l&#8217;onada de calor i tanca els accessos al Montg\u00f3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#website\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"name\":\"Canfali\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"va-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#organization\",\"name\":\"Canfali\",\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"contentUrl\":\"https:\\\/\\\/canfali.com\\\/app\\\/uploads\\\/2025\\\/12\\\/canfali_marina_alta_logo.png\",\"width\":225,\"height\":225,\"caption\":\"Canfali\"},\"image\":{\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-es.facebook.com\\\/CANFALIMarinaAlta\",\"https:\\\/\\\/x.com\\\/canfalima\",\"https:\\\/\\\/www.instagram.com\\\/canfalimarinaalta\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/#\\\/schema\\\/person\\\/9c651adc904f3c4e0243f54407751557\",\"name\":\"Bolta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"va-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/550a5d97fe3cfba5caf077b9600e46529e1977e9d14396836e775d6d9d895a81?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/550a5d97fe3cfba5caf077b9600e46529e1977e9d14396836e775d6d9d895a81?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/550a5d97fe3cfba5caf077b9600e46529e1977e9d14396836e775d6d9d895a81?s=96&d=mm&r=g\",\"caption\":\"Bolta\"},\"url\":\"https:\\\/\\\/canfali.com\\\/ca-es\\\/author\\\/bolta\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9nia activa l'alerta taronja per l'onada de calor i tanca els accessos al Montg\u00f3 - Canfali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/","og_locale":"en_US","og_type":"article","og_title":"D\u00e9nia activa l'alerta taronja per l'onada de calor i tanca els accessos al Montg\u00f3","og_description":"Davant l&#8217;episodi de temperatures extremes que afecta la Comunitat Valenciana, l&#8217;Ajuntament de D\u00e9nia ha activat un paquet de&hellip;","og_url":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/","og_site_name":"Canfali","article_publisher":"https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","article_published_time":"2026-07-15T09:20:27+00:00","article_modified_time":"2026-07-15T09:23:07+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/canfali.com\/app\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg","type":"image\/jpeg"}],"author":"Bolta","twitter_card":"summary_large_image","twitter_creator":"@canfalima","twitter_site":"@canfalima","twitter_misc":{"Written by":"Bolta","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#article","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/"},"author":{"name":"Bolta","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/9c651adc904f3c4e0243f54407751557"},"headline":"D\u00e9nia activa l&#8217;alerta taronja per l&#8217;onada de calor i tanca els accessos al Montg\u00f3","datePublished":"2026-07-15T09:20:27+00:00","dateModified":"2026-07-15T09:23:07+00:00","mainEntityOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/"},"wordCount":355,"publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg","keywords":["d\u00e9nia","onada de calor","Parc Natural del Montg\u00f3","Policia Local"],"articleSection":["Municipal"],"inLanguage":"va-ES","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/canfali.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/","url":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/","name":"D\u00e9nia activa l'alerta taronja per l'onada de calor i tanca els accessos al Montg\u00f3 - Canfali","isPartOf":{"@id":"https:\/\/canfali.com\/ca-es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#primaryimage"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#primaryimage"},"thumbnailUrl":"https:\/\/canfali.com\/app\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg","datePublished":"2026-07-15T09:20:27+00:00","dateModified":"2026-07-15T09:23:07+00:00","breadcrumb":{"@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#breadcrumb"},"inLanguage":"va-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/"]}]},{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#primaryimage","url":"https:\/\/canfali.com\/app\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2026\/07\/WhatsApp-Image-2026-07-15-at-07.58.59-1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/canfali.com\/ca-es\/denia-activa-lalerta-taronja-per-lonada-de-calor-i-tanca-els-accessos-al-montgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/canfali.com\/ca-es\/"},{"@type":"ListItem","position":2,"name":"D\u00e9nia activa l&#8217;alerta taronja per l&#8217;onada de calor i tanca els accessos al Montg\u00f3"}]},{"@type":"WebSite","@id":"https:\/\/canfali.com\/ca-es\/#website","url":"https:\/\/canfali.com\/ca-es\/","name":"Canfali","description":"","publisher":{"@id":"https:\/\/canfali.com\/ca-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canfali.com\/ca-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"va-ES"},{"@type":"Organization","@id":"https:\/\/canfali.com\/ca-es\/#organization","name":"Canfali","url":"https:\/\/canfali.com\/ca-es\/","logo":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/","url":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","contentUrl":"https:\/\/canfali.com\/app\/uploads\/2025\/12\/canfali_marina_alta_logo.png","width":225,"height":225,"caption":"Canfali"},"image":{"@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-es.facebook.com\/CANFALIMarinaAlta","https:\/\/x.com\/canfalima","https:\/\/www.instagram.com\/canfalimarinaalta\/"]},{"@type":"Person","@id":"https:\/\/canfali.com\/ca-es\/#\/schema\/person\/9c651adc904f3c4e0243f54407751557","name":"Bolta","image":{"@type":"ImageObject","inLanguage":"va-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/550a5d97fe3cfba5caf077b9600e46529e1977e9d14396836e775d6d9d895a81?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/550a5d97fe3cfba5caf077b9600e46529e1977e9d14396836e775d6d9d895a81?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/550a5d97fe3cfba5caf077b9600e46529e1977e9d14396836e775d6d9d895a81?s=96&d=mm&r=g","caption":"Bolta"},"url":"https:\/\/canfali.com\/ca-es\/author\/bolta\/"}]}},"_links":{"self":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/105057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/comments?post=105057"}],"version-history":[{"count":1,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/105057\/revisions"}],"predecessor-version":[{"id":105058,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/posts\/105057\/revisions\/105058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media\/105055"}],"wp:attachment":[{"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/media?parent=105057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/categories?post=105057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canfali.com\/ca-es\/wp-json\/wp\/v2\/tags?post=105057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}